{"id":146,"count":0,"description":"","link":"https:\/\/annaalbert.com\/es\/category\/talleres\/","name":"Talleres","slug":"talleres","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Talleres archivos - Art en Seda<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talleres archivos - Art en Seda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/annaalbert.com\/es\/category\/talleres\/\" \/>\n<meta property=\"og:site_name\" content=\"Art en Seda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/category\\\/talleres\\\/\",\"url\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/category\\\/talleres\\\/\",\"name\":\"Talleres archivos - Art en Seda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/category\\\/talleres\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/category\\\/talleres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talleres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/\",\"name\":\"Art en Seda\",\"description\":\"Productos de seda pintada a mano, asi como cursos, talleres, experiencias por la artesana Anna Albert\",\"publisher\":{\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#organization\",\"name\":\"Art en Seda by Anna Albert\",\"url\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/annaalbert.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/horitzontal_fonsblanc-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/annaalbert.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/horitzontal_fonsblanc-scaled.jpg\",\"width\":2560,\"height\":779,\"caption\":\"Art en Seda by Anna Albert\"},\"image\":{\"@id\":\"https:\\\/\\\/annaalbert.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talleres archivos - Art en Seda","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Talleres archivos - Art en Seda","og_url":"https:\/\/annaalbert.com\/es\/category\/talleres\/","og_site_name":"Art en Seda","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/annaalbert.com\/es\/category\/talleres\/","url":"https:\/\/annaalbert.com\/es\/category\/talleres\/","name":"Talleres archivos - Art en Seda","isPartOf":{"@id":"https:\/\/annaalbert.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/annaalbert.com\/es\/category\/talleres\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/annaalbert.com\/es\/category\/talleres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/annaalbert.com\/es\/"},{"@type":"ListItem","position":2,"name":"Talleres"}]},{"@type":"WebSite","@id":"https:\/\/annaalbert.com\/es\/#website","url":"https:\/\/annaalbert.com\/es\/","name":"Art en Seda","description":"Productos de seda pintada a mano, asi como cursos, talleres, experiencias por la artesana Anna Albert","publisher":{"@id":"https:\/\/annaalbert.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/annaalbert.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/annaalbert.com\/es\/#organization","name":"Art en Seda by Anna Albert","url":"https:\/\/annaalbert.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/annaalbert.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/annaalbert.com\/wp-content\/uploads\/2021\/01\/horitzontal_fonsblanc-scaled.jpg","contentUrl":"https:\/\/annaalbert.com\/wp-content\/uploads\/2021\/01\/horitzontal_fonsblanc-scaled.jpg","width":2560,"height":779,"caption":"Art en Seda by Anna Albert"},"image":{"@id":"https:\/\/annaalbert.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/annaalbert.com\/es\/wp-json\/wp\/v2\/categories\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/annaalbert.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/annaalbert.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/annaalbert.com\/es\/wp-json\/wp\/v2\/posts?categories=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}